{"id":2125963,"date":"2025-08-13T15:13:39","date_gmt":"2025-08-13T13:13:39","guid":{"rendered":"https:\/\/www.hoppe.com\/fr-fr\/?p=2125963"},"modified":"2026-03-04T09:25:03","modified_gmt":"2026-03-04T08:25:03","slug":"minilock-pratique-sans-cle","status":"publish","type":"post","link":"https:\/\/www.hoppe.com\/fr-fr\/minilock-pratique-sans-cle\/","title":{"rendered":"MiniLock \u2013 Pratique. Sans cl\u00e9."},"content":{"rendered":"<section class=\"wp-bootstrap-blocks-container has--bg-white\">\n\t<div class=\"container\">\n\t\t\n<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n\n\n<div class=\"col-12 col-md-6\">\n\t\t\t\n\n<h2 class=\"wp-block-heading\">Rosace pour poign\u00e9e de porte avec verrouillage int\u00e9gr\u00e9<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><strong><strong>Une solution de verrouillage pratique et discr\u00e8te pour les portes int\u00e9rieures bec de cane<\/strong><\/strong><\/strong><\/li>\n\n\n\n<li><strong><strong><strong>Large choix de formes de poign\u00e9es<\/strong><\/strong><\/strong><\/li>\n\n\n\n<li><strong>R\u00e9pond aux exigences de la norme DIN EN 1906, grade 3 de la cat\u00e9gorie d\u2019utilisation (adapt\u00e9e au secteur tertiaire \u00e0 fr\u00e9quentation \u00e9lev\u00e9e)<\/strong><\/li>\n<\/ul>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-3 text-md-end\">\n\t\t\t\n<div class=\"wp-bootstrap-blocks-button\">\n\t<a\n\t\thref=\"#Pressekontakt\"\n\t\t\t\t\t\tclass=\"btn w-75 btn-outline-primary w-75 btn-outline-primary\"\n\t>\n\t\tContact presse\t<\/a>\n<\/div>\n\n\n<div class=\"wp-bootstrap-blocks-button\">\n\t<a\n\t\thref=\"#Downloads\"\n\t\t\t\t\t\tclass=\"btn w-75 btn-outline-primary w-75 btn-outline-primary\"\n\t>\n\t\tT\u00e9l\u00e9chargements\t<\/a>\n<\/div>\n\n\t<\/div>\n\n<\/div>\n\n\n<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n\n\n<div class=\"col-12 col-md-6\">\n\t\t\t\n\n<figure class=\"wp-block-image size-large img-fluid text-left\"><img decoding=\"async\" src=\"https:\/\/www.hoppe.com\/de-de\/wp-content\/uploads\/2025\/07\/HOPPE-Contentbild-PR-MiniLock-Lupe-1-1360-x-876-1024x660.jpg\" alt=\"Ligne Macau, aspect laiton satin\u00e9 clair\nIllustration : M1646-42VR-F78-1-R-Motiv1-nW.jpg\" class=\"wp-image-84210\" title=\"Ligne Macau, aspect laiton satin\u00e9 clair Illustration : M1646-42VR-F78-1-R-Motiv1-nW.jpg\"\/><figcaption class=\"wp-element-caption\"><strong>Ligne<\/strong> <strong>Macau, aspect laiton satin\u00e9 clair<br><\/strong>Illustration : M1646-42VR-F78-1-R-Motiv1-nW.jpg<\/figcaption><\/figure>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-3 text-md-end\">\n\t\t\t\t<\/div>\n\n<\/div>\n\n\n<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n\n\n<div class=\"col-12 col-md-6\">\n\t\t\t\n\n<p class=\"wp-block-paragraph\">Les ma\u00eetres d\u2019ouvrage privil\u00e9gient de plus en plus dans les logements modernes un am\u00e9nagement int\u00e9rieur \u00e9pur\u00e9. Dans ce contexte, les portes int\u00e9rieures sans percement pour rosace de fonction (bec de cane) rencontrent un fort succ\u00e8s. Il n\u2019est donc pas possible de fermer \u00e0 cl\u00e9 ces portes de mani\u00e8re traditionnelle. Ce sont donc des poign\u00e9es verrouillables directement sur la poign\u00e9e qui sont install\u00e9es sur ces portes, comme par exemple dans une salle de bain, une chambre ou encore un bureau. Contrairement aux autres syst\u00e8mes existants, MiniLock int\u00e8gre le m\u00e9canisme de verrouillage directement dans la rosace de b\u00e9quille. R\u00e9sultat : une grande vari\u00e9t\u00e9 de formes de poign\u00e9es disponibles permettant de s\u2019adapter \u00e0 tous les styles. Toutes les poign\u00e9es avec carr\u00e9 \u00e0 montage rapide de HOPPE sont compatibles avec MiniLock. Ind\u00e9pendante du m\u00e9canisme de serrure, cette solution convient \u00e0 toutes les portes sans percement pour \u00ab rosace \u00bb de fonction (bec de cane) et peut \u00eatre install\u00e9e m\u00eame lors d\u2019une r\u00e9novation.<\/p>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n<\/div>\n\n\n<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n\n\n<div class=\"col-12 col-md-6\">\n\t\t\t\n\n<p class=\"wp-block-paragraph\"><strong><strong><strong>Verrouillage discret, sans cl\u00e9<\/strong><\/strong><\/strong><br>Les rosaces MiniLock permettent de condamner une porte int\u00e9rieure sans cl\u00e9. Le bouton de condamnation int\u00e9gr\u00e9 \u00e0 la rosace de b\u00e9quille est facilement accessible. Il suffit de le faire glisser vers le haut avec le pouce pour bloquer la poign\u00e9e. Pour d\u00e9verrouiller, il suffit de glisser le bouton vers le bas. En cas de besoin, la porte peut \u00eatre d\u00e9condamner depuis l\u2019ext\u00e9rieur gr\u00e2ce \u00e0 la fonction de d\u00e9condamnation d\u2019urgence int\u00e9gr\u00e9e dans la rosace.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/hoppegroup.sharepoint.com\/:i:\/s\/files\/EUy_snIZOHJMpo8I1UkBl0IBGoq8hlNTCw6dycnt-acLpQ\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large img-fluid text-left\"><img decoding=\"async\" src=\"https:\/\/www.hoppe.com\/de-de\/wp-content\/uploads\/2025\/07\/HOPPE-Contentbild-PR-MiniLock-2-1360-x-876-1024x660.jpg\" alt=\"Ligne Amsterdam, inox mat\nIllustration 2 : E1400-42VR-F69-Motiv1-nW.jpg\" class=\"wp-image-84208\" title=\"Ligne Amsterdam, inox mat Illustration 2 : E1400-42VR-F69-Motiv1-nW.jpg\"\/><figcaption class=\"wp-element-caption\"><strong>Ligne<\/strong> <strong>Amsterdam, inox mat<br><\/strong>Illustration 2 : E1400-42VR-F69-Motiv1-nW.jpg<\/figcaption><\/figure>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n<\/div>\n\n\n<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n\n\n<div class=\"col-12 col-md-6\">\n\t\t\t\n\n<p class=\"wp-block-paragraph\"><strong><strong>Montage facile et rapide<\/strong><\/strong><br>MiniLock s\u2019installe facilement, sans pr\u00e9paration particuli\u00e8re de la porte. Les \u00e9l\u00e9ments s\u2019assemblent ais\u00e9ment gr\u00e2ce \u00e0 un syst\u00e8me de clips, et une seule vis suffit pour fixer solidement l\u2019ensemble sur la porte. Gr\u00e2ce \u00e0 notre syst\u00e8me carr\u00e9 \u00e0 montage rapide, les poign\u00e9es sont fix\u00e9es durablement et sans jeu.<\/p>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n<\/div>\n\n\n<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n\n\n<div class=\"col-12 col-md-6\">\n\t\t\t\n\n<figure class=\"wp-block-image size-large img-fluid text-left\"><img decoding=\"async\" src=\"https:\/\/www.hoppe.com\/de-de\/wp-content\/uploads\/2025\/07\/HOPPE-Contentbild-PR-MiniLock-1-1360-x-876-1024x660.jpg\" alt=\"Ligne Austin, noir mat\nIllustration 3 : 1769-52VR-F9714M-Motiv1-nW.jpg\" class=\"wp-image-84207\" title=\"Ligne Austin, noir mat Illustration 3 : 1769-52VR-F9714M-Motiv1-nW.jpg\"\/><figcaption class=\"wp-element-caption\"><strong>Ligne<\/strong> <strong>Austin, noir mat<br><\/strong>Illustration 3 : 1769-52VR-F9714M-Motiv1-nW.jpg<\/figcaption><\/figure>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-3 text-md-end\">\n\t\t\t\t<\/div>\n\n<\/div>\n\n\n<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n\n\n<div class=\"col-12 col-md-6\">\n\t\t\t\n\n<p class=\"wp-block-paragraph\"><strong><strong><strong><strong>Large choix de poign\u00e9es et de finitions<\/strong><\/strong><\/strong><\/strong><br>MiniLock est disponible dans plusieurs lignes HOPPE au design affirm\u00e9, comme les incontournables lignes Amsterdam et Hamburg, ou encore la ligne \u00e9l\u00e9gante Macau.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un large panel de finitions tendances permet de personnaliser l\u2019ensemble : inox mat, noir mat, aspect laiton satin\u00e9 ou encore des finitions structur\u00e9es comme le gris sable 2900, le noir 2100 structur\u00e9 ou encore l\u2019aspect corten.<\/p>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n<\/div>\n\n\n<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n\n\n<div class=\"col-12 col-md-6\">\n\t\t\t\n\n<p class=\"wp-block-paragraph\"><strong><strong><strong><strong>Convient \u00e9galement au secteur tertiaire<\/strong><\/strong><\/strong><\/strong><br>Les poign\u00e9es avec MiniLock sont con\u00e7ues pour une utilisation intensive et sont parfaitement adapt\u00e9es pour les b\u00e2timents \u00e0 fr\u00e9quentation \u00e9lev\u00e9e. Elles r\u00e9pondent aux exigences de la norme DIN EN 1906, grade 3 de la cat\u00e9gorie d\u2019utilisation.<\/p>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n<\/div>\n\n\n<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n\n\n<div class=\"col-12 col-md-6\">\n\t\t\t\n\n<a name=\"Downloads\"><\/a>\n\n\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Le groupe HOPPE est le leader dans le d\u00e9veloppement, la fabrication et la commercialisation de poign\u00e9es pour portes et fen\u00eatres. Fond\u00e9e en 1952 \u00e0 Heiligenhaus pr\u00e8s de D\u00fcsseldorf, l\u2019entreprise familiale a son si\u00e8ge en Suisse et des usines en Allemagne, Italie, R\u00e9publique tch\u00e8que et aux \u00c9tats-Unis. Elle emploie environ 2 300 personnes sur plus de 20 filiales commerciales r\u00e9parties sur trois continents et fournit des clients dans plus de 90 pays.<\/p>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n<\/div>\n\n\t<\/div>\n<\/section>\n\n\n<section class=\"wp-bootstrap-blocks-container pb-2 has--bg-white\">\n\t<div class=\"container\">\n\t\t\n<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\n<div class=\"wp-bootstrap-blocks-button\">\n\t<a href=\"https:\/\/hoppegroup.sharepoint.com\/:w:\/s\/files\/EWYzgOVC0sFPkhJ9azCNpjIBEjMxF7Q3AcZDsjphiQ-dMg?e=dlWgSl\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"btn btn-outline-primary d-block\">\n\t\tT\u00e9l\u00e9charger communiqu\u00e9 de presse \u00ab MiniLock \u2013 Pratique. Sans cl\u00e9. \u00bb (DOCX, 0,3 MByte)\t<\/a>\n<\/div>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\n<div class=\"wp-bootstrap-blocks-button\">\n\t<a href=\"https:\/\/hoppegroup.sharepoint.com\/:i:\/s\/files\/ESPFQoNKNmtNmkyV9YJsWicBqONus9-N06wQIxifLTkLAg?e=hsMZ3q\" class=\"btn btn-outline-primary d-block\" target=\"_blank\" rel=\"noopener\">\n\t\tT\u00e9l\u00e9charger l\u2019illustration 1 (JPEG, 5,4 MByte)\t<\/a>\n<\/div>\n\n\n<div class=\"wp-bootstrap-blocks-button\">\n\t<a href=\"https:\/\/hoppegroup.sharepoint.com\/:i:\/s\/files\/EXY9ynEupy9KmIlwvginnHIBt_SEF4sUhvsbPfpGS7Vtgg?e=5jMchv\" class=\"btn btn-outline-primary d-block\" target=\"_blank\" rel=\"noopener\">\n\t\tT\u00e9l\u00e9charger l\u2019illustration 2 (JPEG, 3,6 MByte)\t<\/a>\n<\/div>\n\n\n<div class=\"wp-bootstrap-blocks-button\">\n\t<a href=\"https:\/\/hoppegroup.sharepoint.com\/:i:\/s\/files\/Ed5J2mx0MmpHukbqPlZwInYBVh_Y7B4hmT2bRdevoCbO-Q?e=tdqMpi\" class=\"btn btn-outline-primary d-block\" target=\"_blank\" rel=\"noopener\">\n\t\tT\u00e9l\u00e9charger l\u2019illustration 3 (JPEG, 6,1 MByte)\t<\/a>\n<\/div>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n<\/div>\n\n\t<\/div>\n<\/section>\n\n\n<section class=\"wp-bootstrap-blocks-container has--bg-white\">\n\t<div class=\"container\">\n\t\t\n<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n\n\n<div class=\"col-12 col-md-6\">\n\t\t\t\n\n<h2 class=\"wp-block-heading\">Informations relatives aux images<\/h2>\n\n\n\n<a name=\"Pressekontakt\"><\/a>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n<\/div>\n\n\n<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n\n\n<div class=\"col-12 col-md-6\">\n\t\t\t\n\n<p class=\"wp-block-paragraph\">Nous mettons volontiers \u00e0 votre disposition en libre t\u00e9l\u00e9chargement nos photos pour vos communications relatives aux produits et solutions HOPPE, \u00e0 condition de mentionner que la soci\u00e9t\u00e9 HOPPE en est le propri\u00e9taire. Nous serions ravis de recevoir un exemplaire de vos communications.<\/p>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n<\/div>\n\n\t<\/div>\n<\/section>\n\n\n<section class=\"wp-bootstrap-blocks-container\">\n\t<div class=\"container\">\n\t\t\n<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n\n\n<div class=\"col-12 col-md-6\">\n\t\t\t\n\n<h2 class=\"wp-block-heading\">Contact presse<\/h2>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n<\/div>\n\n\n<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n\n\n<div class=\"col-12 col-md-6\">\n\t\t\t\n\n<p class=\"wp-block-paragraph\">HOPPE AG<br>Rapha\u00eblle Rajber<br>27, rue des trois Fronti\u00e8res<br>FR-68110 Illzach<br>Tel. +33 (0)3 89 31 11 07<br><a href=\"mailto:raphaelle.rajber@hoppe.com\">raphaelle.rajber@hoppe.com<\/a><\/p>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-3\">\n\t\t\t\t<\/div>\n\n<\/div>\n\n\t<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>MiniLock \u2013 Pratique. Sans cl\u00e9.<br \/>\nRosace pour poign\u00e9e de porte avec verrouillage int\u00e9gr\u00e9<\/p>\n","protected":false},"author":424,"featured_media":84211,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[14,41,40,56,39],"tags":[],"job_kategorie":[],"class_list":["post-2125963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communique-de-presse","category-design-presse-information","category-espace-objet","category-innovations","category-nouveautes-portail-client"],"acf":[],"author_meta":{"display_name":"rilana-oswald-hoppe","author_link":"https:\/\/www.hoppe.com\/fr-fr\/author\/rilana-oswald-hoppe\/"},"featured_img":"https:\/\/www.hoppe.com\/fr-fr\/wp-content\/uploads\/2025\/07\/HOPPE-Headerbild-PR-MiniLock-Lupe-1920-x-1080-@300dpi-300x169.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.hoppe.com\/fr-fr\/category\/nouveautes\/communique-de-presse\/\" class=\"advgb-post-tax-term\">Communiqu\u00e9 de presse<\/a>","<a href=\"https:\/\/www.hoppe.com\/fr-fr\/category\/nouveautes\/communique-de-presse\/design-presse-information\/\" class=\"advgb-post-tax-term\">Design<\/a>","<a href=\"https:\/\/www.hoppe.com\/fr-fr\/category\/nouveautes\/communique-de-presse\/espace-objet\/\" class=\"advgb-post-tax-term\">Espace objet<\/a>","<a href=\"https:\/\/www.hoppe.com\/fr-fr\/category\/nouveautes\/communique-de-presse\/innovations\/\" class=\"advgb-post-tax-term\">Innovations<\/a>","<a href=\"https:\/\/www.hoppe.com\/fr-fr\/category\/nouveautes-portail-client\/\" class=\"advgb-post-tax-term\">Nouveaut\u00e9s portail client<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Communiqu\u00e9 de presse<\/span>","<span class=\"advgb-post-tax-term\">Design<\/span>","<span class=\"advgb-post-tax-term\">Espace objet<\/span>","<span class=\"advgb-post-tax-term\">Innovations<\/span>","<span class=\"advgb-post-tax-term\">Nouveaut\u00e9s portail client<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publi\u00e9 11 mois il y a","modified":"Mis \u00e0 jour 4 mois il y a"},"absolute_dates":{"created":"Publi\u00e9 le 13. ao\u00fbt 2025","modified":"Mise \u00e0 jour le 4. mars 2026"},"absolute_dates_time":{"created":"Publi\u00e9 le 13. ao\u00fbt 2025 15:13","modified":"Mise \u00e0 jour le 4. mars 2026 9:25"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.hoppe.com\/fr-fr\/wp-json\/wp\/v2\/posts\/2125963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoppe.com\/fr-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoppe.com\/fr-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoppe.com\/fr-fr\/wp-json\/wp\/v2\/users\/424"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoppe.com\/fr-fr\/wp-json\/wp\/v2\/comments?post=2125963"}],"version-history":[{"count":4,"href":"https:\/\/www.hoppe.com\/fr-fr\/wp-json\/wp\/v2\/posts\/2125963\/revisions"}],"predecessor-version":[{"id":2199432,"href":"https:\/\/www.hoppe.com\/fr-fr\/wp-json\/wp\/v2\/posts\/2125963\/revisions\/2199432"}],"wp:attachment":[{"href":"https:\/\/www.hoppe.com\/fr-fr\/wp-json\/wp\/v2\/media?parent=2125963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoppe.com\/fr-fr\/wp-json\/wp\/v2\/categories?post=2125963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoppe.com\/fr-fr\/wp-json\/wp\/v2\/tags?post=2125963"},{"taxonomy":"job_kategorie","embeddable":true,"href":"https:\/\/www.hoppe.com\/fr-fr\/wp-json\/wp\/v2\/job_kategorie?post=2125963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}